{"id":23,"date":"2024-03-10T11:48:10","date_gmt":"2024-03-10T10:48:10","guid":{"rendered":"http:\/\/lathillaye.com\/?page_id=23"},"modified":"2024-03-26T15:04:24","modified_gmt":"2024-03-26T14:04:24","slug":"venir-a-la-thillaye","status":"publish","type":"page","link":"https:\/\/lathillaye.com\/index.php\/venir-a-la-thillaye\/","title":{"rendered":"Venir \u00e0 la Thillaye"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Thillaye se situe dans l&rsquo;arri\u00e8re-pays Deauvillais, \u00e0 8 kms de la gare Trouville-Deauville au sein du bocage normand. Elle est \u00e9galement facilement accessible par  l&rsquo;autoroute A13.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A deux heures de Paris, l&rsquo;immersion cr\u00e9ative est possible !<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"498\" height=\"1024\" src=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-498x1024.jpg\" alt=\"\" class=\"wp-image-117\" srcset=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-498x1024.jpg 498w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-146x300.jpg 146w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-768x1580.jpg 768w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-747x1536.jpg 747w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-996x2048.jpg 996w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/20220519_134221-scaled.jpg 1244w\" sizes=\"auto, (max-width: 498px) 100vw, 498px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Comment \u00eatre accueilli \u00e0 la Thillaye ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre projet artistique est pr\u00e9sent\u00e9, sous la forme d&rsquo;un court texte ou d&rsquo;une vid\u00e9o,  au Conseil d&rsquo;Administration du Fonds de dotation Nicole Andr\u00e9 Hambourg qui d\u00e9cide de votre accueil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour nous en parler, <strong>prenez contact avec V\u00e9ronique Darfeuille, administrateur du Fonds de dotation Nicole Andr\u00e9 Hambourg, au 06.09.18.83.40 ou par mail \u00e0 <a href=\"mailto:lathillaye14@gmail.com\">lathillaye14@gmail.com<\/a> . <\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\"><strong>L&rsquo;acc\u00e8s<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La Thillaye n&rsquo;est pas desservie par les transports en commun. Un moyen de transport personnel est donc indispensable, pour arriver ou vous d\u00e9placer pendant votre s\u00e9jour. <br>Si vous arrivez en train, des taxis sont disponibles \u00e0 la gare de Deauville. Il est prudent de r\u00e9server (t\u00e9l\u00e9phone: 02 31 87 11 11).<br>Plusieurs loueurs de v\u00e9lo, traditionnels et \u00e9lectriques, existent \u00e0 Deauville, dont deux sont implant\u00e9s \u00e0 proximit\u00e9 imm\u00e9diate de la gare:<br>\u2022 Cycles Jamme,11 Avenue de la R\u00e9publique, t\u00e9l\u00e9phone: 02 31 88 40 22, https:\/\/www.cyclesjamme.fr<br>\u2022 Cycle Lucas 88 avenue de la R\u00e9publique, t\u00e9l\u00e9phone 02 31 88 53 55, mail: atelierlucascycles@free.fr.<br>Des loueurs de voiture existent, \u00e0 la gare de Deauville par exemple.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Votre arriv\u00e9e<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous \u00eates attendus les lundi de 14h00 \u00e0 16h30 et les mercredi et vendredi, de 09h00 \u00e0 11h30. D&rsquo;autres jours et heures sont le cas \u00e9ch\u00e9ant possibles entre 09h00 et 16h30.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Votre r\u00e9sidence<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Jusqu&rsquo;\u00e0 quatre voire cinq r\u00e9sidents, vous serez h\u00e9berg\u00e9s dans la Maison des Artistes (le cinqui\u00e8me peut \u00eatre log\u00e9 dans le salon, sur un canap\u00e9-lit). Pour les groupes plus nombreux, des solutions d&rsquo;h\u00e9bergements sont possibles \u00e0 quelques kilom\u00e8tres.<br>Le m\u00e9nage, fait \u00e0 votre arriv\u00e9e, est \u00e0 votre charge pendant toute la dur\u00e9e de votre s\u00e9jour, comme au moment de votre d\u00e9part.<br>Les draps, les couvertures et les serviettes de toilette sont fournis.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/ITECOM-Projet-de-fin-detude-768x1024.jpg\" alt=\"\" class=\"wp-image-176\" srcset=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/ITECOM-Projet-de-fin-detude-768x1024.jpg 768w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/ITECOM-Projet-de-fin-detude-225x300.jpg 225w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/ITECOM-Projet-de-fin-detude-1152x1536.jpg 1152w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/ITECOM-Projet-de-fin-detude.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">ITECOM Projet de fin d&rsquo;\u00e9tudes<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Vos repas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Thillaye ne vous offre pas de service de restauration. Pensez \u00e0 faire les courses avant votre arriv\u00e9e, y compris pour le petit-d\u00e9jeuner du lendemain !<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Espaces accessibles<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;ensemble des jardins, la salle de musique, situ\u00e9e dans la maison principale et les Ateliers d&rsquo;Andr\u00e9 Hambourg vous sont librement accessibles, 24 heures sur 24.<br>L&rsquo;acc\u00e8s \u00e0 l&rsquo;\u00e9tage de la Grande Maison et \u00e0 la Petite Maison ne sont pas possibles actuellement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"935\" src=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/Seance-daquarelle.jpg\" alt=\"\" class=\"wp-image-178\" srcset=\"https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/Seance-daquarelle.jpg 932w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/Seance-daquarelle-300x300.jpg 300w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/Seance-daquarelle-150x150.jpg 150w, https:\/\/lathillaye.com\/wp-content\/uploads\/2024\/03\/Seance-daquarelle-768x770.jpg 768w\" sizes=\"auto, (max-width: 932px) 100vw, 932px\" \/><figcaption class=\"wp-element-caption\">S\u00e9ance d&rsquo;aquarelle<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Acc\u00e8s internet<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les r\u00e9seaux 4G et 5G sont re\u00e7us avec une qualit\u00e9 correcte \u00e0 La Thillaye, selon l&rsquo;\u00e9quipement personnel dont vous disposez.<br>Une connexion WiFi est \u00e0 votre disposition dans la Maison des Artistes et la salle de musique (deux r\u00e9seaux diff\u00e9rents), mais non dans les Ateliers d&rsquo;Andr\u00e9 Hambourg. Les codes d&rsquo;acc\u00e8s vous seront remis \u00e0 votre arriv\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>Votre d\u00e9part<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il peut intervenir les lundi de 14h00 \u00e0 16h30 et les mercredi et vendredi, de 09h00 \u00e0 11h30. D&rsquo;autres jours et heures sont le cas \u00e9ch\u00e9ant possibles entre 09h00 et 16h30. Un compl\u00e9ment de participation vous sera alors demand\u00e9.<br>La caution vers\u00e9e vous sera restitu\u00e9e dans les 8 jours apr\u00e8s votre d\u00e9part.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Thillaye se situe dans l&rsquo;arri\u00e8re-pays Deauvillais, \u00e0 8 kms de la gare Trouville-Deauville au sein du bocage normand. Elle est \u00e9galement facilement accessible par l&rsquo;autoroute A13. A deux heures de Paris, l&rsquo;immersion cr\u00e9ative est possible ! Comment \u00eatre accueilli \u00e0 la Thillaye ? Votre projet artistique est pr\u00e9sent\u00e9, sous la forme d&rsquo;un court texte [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/pages\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":18,"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/pages\/23\/revisions"}],"predecessor-version":[{"id":216,"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/pages\/23\/revisions\/216"}],"wp:attachment":[{"href":"https:\/\/lathillaye.com\/index.php\/wp-json\/wp\/v2\/media?parent=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}